{"id":9,"date":"2021-09-30T18:36:55","date_gmt":"2021-09-30T18:36:55","guid":{"rendered":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/?page_id=9"},"modified":"2023-06-27T11:51:52","modified_gmt":"2023-06-27T11:51:52","slug":"home","status":"publish","type":"page","link":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/","title":{"rendered":"In\u00edcio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9\" class=\"elementor elementor-9\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f9f55a elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no\" data-id=\"5f9f55a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2295be exad-glass-effect-no exad-sticky-section-no\" data-id=\"a2295be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-baaa2df exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"baaa2df\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.2 - 29-01-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"224\" height=\"157\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/home-1.png\" class=\"attachment-large size-large wp-image-300\" alt=\"\" style=\"width:100%;height:70.09%;max-width:224px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f5cbda1 exad-glass-effect-no exad-sticky-section-no\" data-id=\"f5cbda1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e99089 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"7e99089\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ce336b8 exad-glass-effect-no exad-sticky-section-no\" data-id=\"ce336b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"exad-link-anything-wrapper elementor-element elementor-element-a228eef elementor-icon-list--layout-inline elementor-align-left elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-exad-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/wa.me\\\/message\\\/4C6BLVJGS7YPD1&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" data-id=\"a228eef\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(81) 97316-4377<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b704ecc exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"b704ecc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.2 - 29-01-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Whatsapp<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-35216cd exad-glass-effect-no exad-sticky-section-no\" data-id=\"35216cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"exad-link-anything-wrapper elementor-element elementor-element-7d034fa elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-exad-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/goo.gl\\\/maps\\\/2fZUQoyFVACygiSTA&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" data-id=\"7d034fa\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Av. Historiador Pereira da Costa, n\u00ba 520<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06111e9 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"06111e9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Centro, Cabo de Sto Agostinho &#8211; PE<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-52ea29b exad-glass-effect-no exad-sticky-section-no\" data-id=\"52ea29b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"exad-link-anything-wrapper elementor-element elementor-element-08565bd elementor-icon-list--layout-inline elementor-align-right elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-exad-element-link=\"{&quot;url&quot;:&quot;mailto:comunicacao@viegasultraimagem.com.br&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" data-id=\"08565bd\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">comunicacao@viegasultraimagem.com.br<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7e7d37 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"e7e7d37\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: left;\">Entre em contato conosco<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5818a2f elementor-nav-menu__align-center elementor-nav-menu--stretch elementor-nav-menu__text-align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu--toggle elementor-nav-menu--burger exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-nav-menu\" data-id=\"5818a2f\" data-element_type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-nav-menu.min.css\">\t\t\t<nav migration_allowed=\"1\" migrated=\"0\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-5818a2f\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-337\"><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/\" class=\"elementor-item\">In\u00edcio<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-305\"><a href=\"#sobre\" class=\"elementor-item elementor-item-anchor\">Quem Somos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-306\"><a href=\"#servicos\" class=\"elementor-item elementor-item-anchor\">Servi\u00e7os<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-307\"><a href=\"#estrutura\" class=\"elementor-item elementor-item-anchor\">Nossa Estrutura<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-308\"><a href=\"#contato\" class=\"elementor-item elementor-item-anchor\">Contato<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-309\"><a href=\"http:\/\/ansexames.com\/viegas\/\" class=\"elementor-item\">\u00c1rea do Cliente<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5818a2f\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-337\"><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/\" class=\"elementor-item\" tabindex=\"-1\">In\u00edcio<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-305\"><a href=\"#sobre\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Quem Somos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-306\"><a href=\"#servicos\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Servi\u00e7os<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-307\"><a href=\"#estrutura\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Nossa Estrutura<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-308\"><a href=\"#contato\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Contato<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-309\"><a href=\"http:\/\/ansexames.com\/viegas\/\" class=\"elementor-item\" tabindex=\"-1\">\u00c1rea do Cliente<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e01bdb elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"1e01bdb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0cddfa2 exad-glass-effect-no exad-sticky-section-no\" data-id=\"0cddfa2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-489038b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"489038b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"224\" height=\"157\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/home-1.png\" class=\"attachment-large size-large wp-image-300\" alt=\"\" style=\"width:100%;height:70.09%;max-width:224px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c930951 exad-glass-effect-no exad-sticky-section-no\" data-id=\"c930951\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e88005 elementor-nav-menu__align-center elementor-nav-menu--stretch elementor-nav-menu__text-align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu--toggle elementor-nav-menu--burger exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-nav-menu\" data-id=\"0e88005\" data-element_type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav migration_allowed=\"1\" migrated=\"0\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-0e88005\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-337\"><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/\" class=\"elementor-item\">In\u00edcio<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-305\"><a href=\"#sobre\" class=\"elementor-item elementor-item-anchor\">Quem Somos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-306\"><a href=\"#servicos\" class=\"elementor-item elementor-item-anchor\">Servi\u00e7os<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-307\"><a href=\"#estrutura\" class=\"elementor-item elementor-item-anchor\">Nossa Estrutura<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-308\"><a href=\"#contato\" class=\"elementor-item elementor-item-anchor\">Contato<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-309\"><a href=\"http:\/\/ansexames.com\/viegas\/\" class=\"elementor-item\">\u00c1rea do Cliente<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-0e88005\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-337\"><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/\" class=\"elementor-item\" tabindex=\"-1\">In\u00edcio<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-305\"><a href=\"#sobre\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Quem Somos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-306\"><a href=\"#servicos\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Servi\u00e7os<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-307\"><a href=\"#estrutura\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Nossa Estrutura<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-308\"><a href=\"#contato\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Contato<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-309\"><a href=\"http:\/\/ansexames.com\/viegas\/\" class=\"elementor-item\" tabindex=\"-1\">\u00c1rea do Cliente<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5f5ec6 elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"e5f5ec6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74ecfe1 exad-glass-effect-no exad-sticky-section-no\" data-id=\"74ecfe1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a969ff3 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"a969ff3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae6ef2f elementor-hidden-desktop elementor-hidden-tablet exad-glass-effect-no exad-sticky-section-no\" data-id=\"ae6ef2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b684f7 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"2b684f7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fca9088 exad-glass-effect-no exad-sticky-section-no\" data-id=\"fca9088\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a95649 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-menu-anchor\" data-id=\"8a95649\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.2 - 29-01-2023 *\/\nbody.elementor-page .elementor-widget-menu-anchor{margin-bottom:0}<\/style>\t\t<div id=\"sobre\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc4d71 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"4bc4d71\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.2 - 29-01-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h4 class=\"elementor-heading-title elementor-size-default\">QUEM SOMOS<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82ee955 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"82ee955\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">A Ultra-Imagem Viegas \u00e9 um Centro Diagn\u00f3stico especializado em Radiologia e Sa\u00fade Ocupacional. Fundada em 2008 pelos m\u00e9dicos do trabalho e radiologistas Maria Rachel Viegas CRM-PE 12.813 e T\u00falio Br\u00e1ulio Cantalice de Paula CRM-PE 12.159 com o objetivo de atender a popula\u00e7\u00e3o e empresas\u00a0 no Cabo de Santo Agostinho e Regi\u00f5es.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cb1268 elementor-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"7cb1268\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/quem-somos\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Saiba Mais<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d59f28b elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"d59f28b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4661d5d exad-glass-effect-no exad-sticky-section-no\" data-id=\"4661d5d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3b43e6 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"a3b43e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">QUEM SOMOS<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a3b0ed exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"8a3b0ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">A Ultra-Imagem Viegas \u00e9 um Centro Diagn\u00f3stico especializado em Radiologia e Sa\u00fade Ocupacional. Fundada em 2008 pelos m\u00e9dicos do trabalho e radiologistas Maria Rachel Viegas CRM-PE 12.813 e T\u00falio Br\u00e1ulio Cantalice de Paula CRM-PE 12.159 com o objetivo de atender a popula\u00e7\u00e3o e empresas no Cabo de Santo Agostinho e Regi\u00f5es.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03104e5 elementor-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"03104e5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/quem-somos\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Saiba Mais<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68ce281 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"68ce281\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc0c2cf exad-glass-effect-no exad-sticky-section-no\" data-id=\"dc0c2cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a610e13 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-menu-anchor\" data-id=\"a610e13\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"servicos\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9ed17f exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"c9ed17f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nossos Servi\u00e7os<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fa8d81 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"7fa8d81\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-637ea8b exad-glass-effect-no exad-sticky-section-no\" data-id=\"637ea8b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f759d8 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"7f759d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/diagnostico-por-imagem\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2023\/03\/card-radiologia.png\" class=\"attachment-full size-full wp-image-1151\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-df6a1e5 exad-glass-effect-no exad-sticky-section-no\" data-id=\"df6a1e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c1328e exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"3c1328e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/saude-ocupacional\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2023\/03\/card-saude-ocupacional.png\" class=\"attachment-full size-full wp-image-1152\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-983a261 exad-glass-effect-no exad-sticky-section-no\" data-id=\"983a261\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66b638a exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"66b638a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/seguranca-do-trabalho\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"194\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2023\/03\/card-seg-do-trabalho-new.png\" class=\"attachment-full size-full wp-image-1161\" alt=\"\" style=\"width:100%;height:90.65%;max-width:214px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f44f0f4 exad-glass-effect-no exad-sticky-section-no\" data-id=\"f44f0f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d81ac2 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"8d81ac2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/e-social\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"194\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2023\/03\/card-e-social-new.png\" class=\"attachment-full size-full wp-image-1160\" alt=\"\" style=\"width:100%;height:90.65%;max-width:214px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-843b6b8 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"843b6b8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a9c6b9 exad-glass-effect-no exad-sticky-section-no\" data-id=\"9a9c6b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c30cd4 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"1c30cd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">DIAGN\u00d3STICOS REALIZADOS COM M\u00c1XIMA <strong>SEGURAN\u00c7A<\/strong> E <strong>CUIDADO<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afb87f9 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"afb87f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">CONFIRA<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac3dc65 elementor-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"ac3dc65\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"#contato\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"256\" height=\"256\" viewBox=\"0 0 256 256\" xml:space=\"preserve\">\n<desc>Created with Fabric.js 1.7.22<\/desc>\n<defs>\n<\/defs>\n<g transform=\"translate(128 128) scale(0.72 0.72)\" style=\"\">\n\t<g style=\"stroke: none; stroke-width: 0; stroke-dasharray: none; stroke-linecap: butt; stroke-linejoin: miter; stroke-miterlimit: 10; fill: none; fill-rule: nonzero; opacity: 1;\" transform=\"translate(-175.05 -175.05000000000004) scale(3.89 3.89)\">\n\t<polygon points=\"0,39.64 4.28,35.36 45,76.08 85.72,35.36 90,39.64 45,84.64 \" style=\"stroke: none; stroke-width: 1; stroke-dasharray: none; stroke-linecap: butt; stroke-linejoin: miter; stroke-miterlimit: 10; fill: rgb(22,82,164); fill-rule: nonzero; opacity: 1;\" transform=\"  matrix(1 0 0 1 0 0) \"><\/polygon>\n\t<polygon points=\"0,9.64 4.28,5.36 45,46.08 85.72,5.36 90,9.64 45,54.64 \" style=\"stroke: none; stroke-width: 1; stroke-dasharray: none; stroke-linecap: butt; stroke-linejoin: miter; stroke-miterlimit: 10; fill: rgb(22,82,164); fill-rule: nonzero; opacity: 1;\" transform=\"  matrix(1 0 0 1 0 0) \"><\/polygon>\n<\/g>\n<\/g>\n<\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\"><\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce67afc elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"ce67afc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6ba645 exad-glass-effect-no exad-sticky-section-no\" data-id=\"e6ba645\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6a611b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"f6a611b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">DIAGN\u00d3STICOS REALIZADOS COM M\u00c1XIMA <strong>SEGURAN\u00c7A<\/strong> E <strong>CUIDADO<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d66a6d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"7d66a6d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">CONFIRA<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-341fd57 elementor-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"341fd57\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"#sobre\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"256\" height=\"256\" viewBox=\"0 0 256 256\" xml:space=\"preserve\">\n<desc>Created with Fabric.js 1.7.22<\/desc>\n<defs>\n<\/defs>\n<g transform=\"translate(128 128) scale(0.72 0.72)\" style=\"\">\n\t<g style=\"stroke: none; stroke-width: 0; stroke-dasharray: none; stroke-linecap: butt; stroke-linejoin: miter; stroke-miterlimit: 10; fill: none; fill-rule: nonzero; opacity: 1;\" transform=\"translate(-175.05 -175.05000000000004) scale(3.89 3.89)\">\n\t<polygon points=\"0,39.64 4.28,35.36 45,76.08 85.72,35.36 90,39.64 45,84.64 \" style=\"stroke: none; stroke-width: 1; stroke-dasharray: none; stroke-linecap: butt; stroke-linejoin: miter; stroke-miterlimit: 10; fill: rgb(22,82,164); fill-rule: nonzero; opacity: 1;\" transform=\"  matrix(1 0 0 1 0 0) \"><\/polygon>\n\t<polygon points=\"0,9.64 4.28,5.36 45,46.08 85.72,5.36 90,9.64 45,54.64 \" style=\"stroke: none; stroke-width: 1; stroke-dasharray: none; stroke-linecap: butt; stroke-linejoin: miter; stroke-miterlimit: 10; fill: rgb(22,82,164); fill-rule: nonzero; opacity: 1;\" transform=\"  matrix(1 0 0 1 0 0) \"><\/polygon>\n<\/g>\n<\/g>\n<\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\"><\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51b82fc elementor-hidden-mobile elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"51b82fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d3d021f exad-glass-effect-no exad-sticky-section-no\" data-id=\"d3d021f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48ed0ea exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"48ed0ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card01.png\" class=\"attachment-large size-large wp-image-457\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e36fd2f exad-glass-effect-no exad-sticky-section-no\" data-id=\"e36fd2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7c8de5 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"a7c8de5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card02.png\" class=\"attachment-large size-large wp-image-464\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b3fc54d exad-glass-effect-no exad-sticky-section-no\" data-id=\"b3fc54d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2058618 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"2058618\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card03.png\" class=\"attachment-large size-large wp-image-465\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2d6f962 exad-glass-effect-no exad-sticky-section-no\" data-id=\"2d6f962\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20cd038 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"20cd038\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card04.png\" class=\"attachment-large size-large wp-image-466\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-bbf5717 exad-glass-effect-no exad-sticky-section-no\" data-id=\"bbf5717\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3779bd exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"f3779bd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card05.png\" class=\"attachment-large size-large wp-image-467\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c878f4 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"9c878f4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-befec55 exad-glass-effect-no exad-sticky-section-no\" data-id=\"befec55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fe544b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"7fe544b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card01.png\" class=\"attachment-large size-large wp-image-457\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-1948f3b exad-glass-effect-no exad-sticky-section-no\" data-id=\"1948f3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afd8419 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"afd8419\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card02.png\" class=\"attachment-large size-large wp-image-464\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-b45f660 exad-glass-effect-no exad-sticky-section-no\" data-id=\"b45f660\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f31124 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"3f31124\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card03.png\" class=\"attachment-large size-large wp-image-465\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-6b7419c exad-glass-effect-no exad-sticky-section-no\" data-id=\"6b7419c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30379ec exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"30379ec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card04.png\" class=\"attachment-large size-large wp-image-466\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-e28be77 exad-glass-effect-no exad-sticky-section-no\" data-id=\"e28be77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-273029e exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"273029e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card05.png\" class=\"attachment-large size-large wp-image-467\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-460f1b5 exad-glass-effect-no exad-sticky-section-no\" data-id=\"460f1b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b661cb1 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"b661cb1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card06.png\" class=\"attachment-large size-large wp-image-471\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-000b4ab elementor-hidden-mobile elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"000b4ab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2a7c04a exad-glass-effect-no exad-sticky-section-no\" data-id=\"2a7c04a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d29d27f exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"d29d27f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card06.png\" class=\"attachment-large size-large wp-image-471\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-265201b exad-glass-effect-no exad-sticky-section-no\" data-id=\"265201b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-976676c exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"976676c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/saude-ocupacional\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card07.png\" class=\"attachment-large size-large wp-image-472\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a075242 exad-glass-effect-no exad-sticky-section-no\" data-id=\"a075242\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db6b9dd exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"db6b9dd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.labet.com.br\/comprar-exames\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card08.png\" class=\"attachment-large size-large wp-image-473\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-47fb787 exad-glass-effect-no exad-sticky-section-no\" data-id=\"47fb787\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a636927 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"a636927\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card09.png\" class=\"attachment-large size-large wp-image-474\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-046dfdc exad-glass-effect-no exad-sticky-section-no\" data-id=\"046dfdc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24177b0 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"24177b0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card10.png\" class=\"attachment-large size-large wp-image-475\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4dc0b6 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"f4dc0b6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3426d53 exad-glass-effect-no exad-sticky-section-no\" data-id=\"3426d53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2af0e6 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"c2af0e6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/saude-ocupacional\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card07.png\" class=\"attachment-large size-large wp-image-472\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-eeb5b43 exad-glass-effect-no exad-sticky-section-no\" data-id=\"eeb5b43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8c0ade exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"d8c0ade\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.labet.com.br\/comprar-exames\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card08.png\" class=\"attachment-large size-large wp-image-473\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9d4de11 exad-glass-effect-no exad-sticky-section-no\" data-id=\"9d4de11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22363b2 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"22363b2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card09.png\" class=\"attachment-large size-large wp-image-474\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-49ca43e exad-glass-effect-no exad-sticky-section-no\" data-id=\"49ca43e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2c597b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"b2c597b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"192\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/card10.png\" class=\"attachment-large size-large wp-image-475\" alt=\"\" style=\"width:100%;height:90.14%;max-width:213px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d0990c elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"2d0990c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b71a36 exad-glass-effect-no exad-sticky-section-no\" data-id=\"5b71a36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ba04d4 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-menu-anchor\" data-id=\"2ba04d4\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"estrutura\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b441bf8 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"b441bf8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nossa Estrutura <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-812c3d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"812c3d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64cd79c exad-glass-effect-no exad-sticky-section-no\" data-id=\"64cd79c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eb905f exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-shortcode\" data-id=\"1eb905f\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"envira-gallery-wrap-756\" class=\"envira-gallery-wrap envira-gallery-theme-base envira-lightbox-theme-base\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><div data-row-height=\"\" data-gallery-theme=\"\" id=\"envira-gallery-756\" class=\"envira-gallery-public  envira-gallery-3-columns envira-clear enviratope envira-gallery-css-animations\" data-envira-columns=\"3\"><div id=\"envira-gallery-item-758\" class=\"envira-gallery-item enviratope-item envira-gallery-item-1 envira-lazy-load\" style=\"padding-left: 15px; padding-bottom: 30px; padding-right: 15px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/clinico.jpeg\" class=\"envira-gallery-756 envira-gallery-link\" rel=\"enviragallery756\" title=\"\" data-envira-caption=\"\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-758\" class=\"envira-gallery-image envira-gallery-image-1\" data-envira-index=\"1\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/clinico-1024x768-640x480.jpeg\" data-envira-src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/clinico-1024x768-640x480.jpeg\" data-envira-gallery-id=\"756\" data-envira-item-id=\"758\" data-envira-caption=\"\" alt=\"\" title=\"\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/clinico-1024x768-640x480.jpeg 400w,https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/clinico-1024x768-640x480.jpeg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-759\" class=\"envira-gallery-item enviratope-item envira-gallery-item-2 envira-lazy-load\" style=\"padding-left: 15px; padding-bottom: 30px; padding-right: 15px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/densitometria.png\" class=\"envira-gallery-756 envira-gallery-link\" rel=\"enviragallery756\" title=\"\" data-envira-caption=\"\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-759\" class=\"envira-gallery-image envira-gallery-image-2\" data-envira-index=\"2\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/densitometria-640x480.png\" data-envira-src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/densitometria-640x480.png\" data-envira-gallery-id=\"756\" data-envira-item-id=\"759\" data-envira-caption=\"\" alt=\"\" title=\"\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/densitometria-640x480.png 400w,https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/densitometria-640x480.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-760\" class=\"envira-gallery-item enviratope-item envira-gallery-item-3 envira-lazy-load\" style=\"padding-left: 15px; padding-bottom: 30px; padding-right: 15px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0177-scaled.jpg\" class=\"envira-gallery-756 envira-gallery-link\" rel=\"enviragallery756\" title=\"\" data-envira-caption=\"\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-760\" class=\"envira-gallery-image envira-gallery-image-3\" data-envira-index=\"3\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0177-1024x768-640x480.jpg\" data-envira-src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0177-1024x768-640x480.jpg\" data-envira-gallery-id=\"756\" data-envira-item-id=\"760\" data-envira-caption=\"\" alt=\"\" title=\"\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0177-1024x768-640x480.jpg 400w,https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0177-1024x768-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-761\" class=\"envira-gallery-item enviratope-item envira-gallery-item-4 envira-lazy-load\" style=\"padding-left: 15px; padding-bottom: 30px; padding-right: 15px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0182-scaled.jpg\" class=\"envira-gallery-756 envira-gallery-link\" rel=\"enviragallery756\" title=\"\" data-envira-caption=\"\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-761\" class=\"envira-gallery-image envira-gallery-image-4\" data-envira-index=\"4\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0182-1024x768-640x480.jpg\" data-envira-src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0182-1024x768-640x480.jpg\" data-envira-gallery-id=\"756\" data-envira-item-id=\"761\" data-envira-caption=\"\" alt=\"\" title=\"\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0182-1024x768-640x480.jpg 400w,https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0182-1024x768-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-1199\" class=\"envira-gallery-item enviratope-item envira-gallery-item-5 envira-lazy-load\" style=\"padding-left: 15px; padding-bottom: 30px; padding-right: 15px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/ULTRA-222-640x480-1.png\" class=\"envira-gallery-756 envira-gallery-link\" rel=\"enviragallery756\" title=\"\" data-envira-caption=\"\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-1199\" class=\"envira-gallery-image envira-gallery-image-5\" data-envira-index=\"5\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/ULTRA-222-640x480-1.png\" data-envira-src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/ULTRA-222-640x480-1.png\" data-envira-gallery-id=\"756\" data-envira-item-id=\"1199\" data-envira-caption=\"\" alt=\"\" title=\"\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/ULTRA-222-640x480-1.png 400w,https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/ULTRA-222-640x480-1.png 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><div id=\"envira-gallery-item-767\" class=\"envira-gallery-item enviratope-item envira-gallery-item-6 envira-lazy-load\" style=\"padding-left: 15px; padding-bottom: 30px; padding-right: 15px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay  envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay  envira-gallery-bottom-right\"><\/div><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/onibus-6.jpg\" class=\"envira-gallery-756 envira-gallery-link\" rel=\"enviragallery756\" title=\"\" data-envira-caption=\"\" data-envira-retina=\"\" data-thumbnail=\"\"  itemprop=\"contentUrl\"><div class=\"envira-lazy\" data-test-width=\"640\" data-test-height=\"480\" style=\"padding-bottom:75%;\"><img decoding=\"async\" id=\"envira-gallery-image-767\" class=\"envira-gallery-image envira-gallery-image-6\" data-envira-index=\"6\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/onibus-6-1024x768-640x480.jpg\" data-envira-src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/onibus-6-1024x768-640x480.jpg\" data-envira-gallery-id=\"756\" data-envira-item-id=\"767\" data-envira-caption=\"\" alt=\"\" title=\"\"  itemprop=\"thumbnailUrl\" data-envira-srcset=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/onibus-6-1024x768-640x480.jpg 400w,https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/onibus-6-1024x768-640x480.jpg 2x\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><\/div><\/a><\/div><\/div><\/div><\/div><noscript><img decoding=\"async\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/clinico.jpeg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/densitometria.png\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0177-scaled.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/IMG-0182-scaled.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/ULTRA-222-640x480-1.png\" alt=\"\" \/><img decoding=\"async\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2022\/01\/onibus-6.jpg\" alt=\"\" \/><\/noscript>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f75beff elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"f75beff\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08727d4 exad-glass-effect-no exad-sticky-section-no\" data-id=\"08727d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d0c255 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"5d0c255\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Institucional<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be8c76c elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"be8c76c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-226b2b8 exad-glass-effect-no exad-sticky-section-no\" data-id=\"226b2b8\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f888708 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"f888708\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"68\" height=\"58\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/visao.png\" class=\"attachment-large size-large wp-image-412\" alt=\"\" style=\"width:100%;height:85.29%;max-width:68px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4304d6d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-exad-modal-popup\" data-id=\"4304d6d\" data-element_type=\"widget\" data-widget_type=\"exad-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"exad-modal\">\n\t\t\t<div class=\"exad-modal-wrapper\">\n\n\t\t\t\t<div class=\"exad-modal-button exad-modal-btn-fixed-width-\">\n\t\t\t\t\t<a href=\"#\" class=\"exad-modal-image-action image-modal\" data-exad-modal=\"#exad-modal-4304d6d\" data-exad-overlay=\"yes\" >\n\t\t\t\t\t\t<span class=\"exad-modal-action-icon-\">\n\t\t\t\t\t\t\tMISS\u00c3O\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"exad-modal-4304d6d\" class=\"exad-modal-item modal-vimeo zoom-in shortcode exad-content-overflow-x-yes exad-content-overflow-y-yes\" >\n\t\t\t\t\t<div class=\"exad-modal-content\">\n\t\t\t\t\t\t<div class=\"exad-modal-element \">\n\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"688\" class=\"elementor elementor-688\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4701fd elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"b4701fd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f34f13 exad-glass-effect-no exad-sticky-section-no\" data-id=\"9f34f13\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13ed9af exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"13ed9af\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Miss\u00e3o<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0aab1b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"f0aab1b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Cuidar da sa\u00fade integral das empresas oferecendo atendimentos em Medicina do Trabalho e Radiodiagn\u00f3stico com \u00e9tica, qualidade e responsabilidade.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<div class=\"exad-close-btn\">\n\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"exad-modal-overlay\" data-exad_overlay_click_close=\"yes\"><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7640bed exad-glass-effect-no exad-sticky-section-no\" data-id=\"7640bed\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fd3617 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"2fd3617\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"61\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/valores.png\" class=\"attachment-large size-large wp-image-411\" alt=\"\" style=\"width:100%;height:84.72%;max-width:72px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0d874a exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-exad-modal-popup\" data-id=\"d0d874a\" data-element_type=\"widget\" data-widget_type=\"exad-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"exad-modal\">\n\t\t\t<div class=\"exad-modal-wrapper\">\n\n\t\t\t\t<div class=\"exad-modal-button exad-modal-btn-fixed-width-\">\n\t\t\t\t\t<a href=\"#\" class=\"exad-modal-image-action image-modal\" data-exad-modal=\"#exad-modal-d0d874a\" data-exad-overlay=\"yes\" >\n\t\t\t\t\t\t<span class=\"exad-modal-action-icon-\">\n\t\t\t\t\t\t\tVALORES\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"exad-modal-d0d874a\" class=\"exad-modal-item modal-vimeo zoom-in shortcode exad-content-overflow-x-yes exad-content-overflow-y-yes\" >\n\t\t\t\t\t<div class=\"exad-modal-content\">\n\t\t\t\t\t\t<div class=\"exad-modal-element \">\n\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"692\" class=\"elementor elementor-692\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6895b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"a6895b3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f14e5c exad-glass-effect-no exad-sticky-section-no\" data-id=\"3f14e5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f105de exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6f105de\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Valores<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ea1d30 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"6ea1d30\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Trabalho em equipe e desenvolvimento profissional;<br \/>Gest\u00e3o inovadora e participativa;<br \/>Responsabilidade e seguran\u00e7a nos servi\u00e7os prestados;<br \/>Comprometimento com o crescimento da empresa.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<div class=\"exad-close-btn\">\n\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"exad-modal-overlay\" data-exad_overlay_click_close=\"yes\"><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cdb32f8 exad-glass-effect-no exad-sticky-section-no\" data-id=\"cdb32f8\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7991de1 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"7991de1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"59\" height=\"59\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/missao.png\" class=\"attachment-large size-large wp-image-410\" alt=\"\" style=\"width:100%;height:100%;max-width:59px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c8fb13 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-exad-modal-popup\" data-id=\"8c8fb13\" data-element_type=\"widget\" data-widget_type=\"exad-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"exad-modal\">\n\t\t\t<div class=\"exad-modal-wrapper\">\n\n\t\t\t\t<div class=\"exad-modal-button exad-modal-btn-fixed-width-\">\n\t\t\t\t\t<a href=\"#\" class=\"exad-modal-image-action image-modal\" data-exad-modal=\"#exad-modal-8c8fb13\" data-exad-overlay=\"yes\" >\n\t\t\t\t\t\t<span class=\"exad-modal-action-icon-\">\n\t\t\t\t\t\t\tPROP\u00d3SITO\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"exad-modal-8c8fb13\" class=\"exad-modal-item modal-vimeo zoom-in shortcode exad-content-overflow-x-yes exad-content-overflow-y-yes\" >\n\t\t\t\t\t<div class=\"exad-modal-content\">\n\t\t\t\t\t\t<div class=\"exad-modal-element \">\n\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"696\" class=\"elementor elementor-696\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ee384f elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-sticky-section-no\" data-id=\"2ee384f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72dc993 exad-glass-effect-no exad-sticky-section-no\" data-id=\"72dc993\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73aabc5 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"73aabc5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prop\u00f3sito<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f613a9d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"f613a9d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Garantir a integridade da sa\u00fade das pessoas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<div class=\"exad-close-btn\">\n\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"exad-modal-overlay\" data-exad_overlay_click_close=\"yes\"><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eab567b elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"eab567b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dfc1141 exad-glass-effect-no exad-sticky-section-no\" data-id=\"dfc1141\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-521ee2c exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"521ee2c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"68\" height=\"58\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/visao.png\" class=\"attachment-large size-large wp-image-412\" alt=\"\" style=\"width:100%;height:85.29%;max-width:68px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07f25d1 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-exad-modal-popup\" data-id=\"07f25d1\" data-element_type=\"widget\" data-widget_type=\"exad-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"exad-modal\">\n\t\t\t<div class=\"exad-modal-wrapper\">\n\n\t\t\t\t<div class=\"exad-modal-button exad-modal-btn-fixed-width-\">\n\t\t\t\t\t<a href=\"#\" class=\"exad-modal-image-action image-modal\" data-exad-modal=\"#exad-modal-07f25d1\" data-exad-overlay=\"yes\" >\n\t\t\t\t\t\t<span class=\"exad-modal-action-icon-\">\n\t\t\t\t\t\t\tMISS\u00c3O\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"exad-modal-07f25d1\" class=\"exad-modal-item modal-vimeo zoom-in shortcode exad-content-overflow-x-yes exad-content-overflow-y-yes\" >\n\t\t\t\t\t<div class=\"exad-modal-content\">\n\t\t\t\t\t\t<div class=\"exad-modal-element \">\n\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"688\" class=\"elementor elementor-688\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4701fd elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"b4701fd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f34f13 exad-glass-effect-no exad-sticky-section-no\" data-id=\"9f34f13\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13ed9af exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"13ed9af\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Miss\u00e3o<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0aab1b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"f0aab1b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Cuidar da sa\u00fade integral das empresas oferecendo atendimentos em Medicina do Trabalho e Radiodiagn\u00f3stico com \u00e9tica, qualidade e responsabilidade.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<div class=\"exad-close-btn\">\n\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"exad-modal-overlay\" data-exad_overlay_click_close=\"yes\"><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-679769b exad-glass-effect-no exad-sticky-section-no\" data-id=\"679769b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d39d1ad exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"d39d1ad\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"72\" height=\"61\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/valores.png\" class=\"attachment-large size-large wp-image-411\" alt=\"\" style=\"width:100%;height:84.72%;max-width:72px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8d53e1 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-exad-modal-popup\" data-id=\"b8d53e1\" data-element_type=\"widget\" data-widget_type=\"exad-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"exad-modal\">\n\t\t\t<div class=\"exad-modal-wrapper\">\n\n\t\t\t\t<div class=\"exad-modal-button exad-modal-btn-fixed-width-\">\n\t\t\t\t\t<a href=\"#\" class=\"exad-modal-image-action image-modal\" data-exad-modal=\"#exad-modal-b8d53e1\" data-exad-overlay=\"yes\" >\n\t\t\t\t\t\t<span class=\"exad-modal-action-icon-\">\n\t\t\t\t\t\t\tVALORES\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"exad-modal-b8d53e1\" class=\"exad-modal-item modal-vimeo zoom-in shortcode exad-content-overflow-x-yes exad-content-overflow-y-yes\" >\n\t\t\t\t\t<div class=\"exad-modal-content\">\n\t\t\t\t\t\t<div class=\"exad-modal-element \">\n\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"692\" class=\"elementor elementor-692\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6895b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"a6895b3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f14e5c exad-glass-effect-no exad-sticky-section-no\" data-id=\"3f14e5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f105de exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6f105de\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Valores<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ea1d30 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"6ea1d30\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Trabalho em equipe e desenvolvimento profissional;<br \/>Gest\u00e3o inovadora e participativa;<br \/>Responsabilidade e seguran\u00e7a nos servi\u00e7os prestados;<br \/>Comprometimento com o crescimento da empresa.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<div class=\"exad-close-btn\">\n\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"exad-modal-overlay\" data-exad_overlay_click_close=\"yes\"><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-18000e5 exad-glass-effect-no exad-sticky-section-no\" data-id=\"18000e5\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89ce6e4 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"89ce6e4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"59\" height=\"59\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/missao.png\" class=\"attachment-large size-large wp-image-410\" alt=\"\" style=\"width:100%;height:100%;max-width:59px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05075c0 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-exad-modal-popup\" data-id=\"05075c0\" data-element_type=\"widget\" data-widget_type=\"exad-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"exad-modal\">\n\t\t\t<div class=\"exad-modal-wrapper\">\n\n\t\t\t\t<div class=\"exad-modal-button exad-modal-btn-fixed-width-\">\n\t\t\t\t\t<a href=\"#\" class=\"exad-modal-image-action image-modal\" data-exad-modal=\"#exad-modal-05075c0\" data-exad-overlay=\"yes\" >\n\t\t\t\t\t\t<span class=\"exad-modal-action-icon-\">\n\t\t\t\t\t\t\tPROP\u00d3SITO\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"exad-modal-05075c0\" class=\"exad-modal-item modal-vimeo zoom-in shortcode exad-content-overflow-x-yes exad-content-overflow-y-yes\" >\n\t\t\t\t\t<div class=\"exad-modal-content\">\n\t\t\t\t\t\t<div class=\"exad-modal-element \">\n\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"696\" class=\"elementor elementor-696\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ee384f elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-sticky-section-no\" data-id=\"2ee384f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72dc993 exad-glass-effect-no exad-sticky-section-no\" data-id=\"72dc993\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73aabc5 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"73aabc5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prop\u00f3sito<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f613a9d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"f613a9d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Garantir a integridade da sa\u00fade das pessoas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<div class=\"exad-close-btn\">\n\t\t\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"exad-modal-overlay\" data-exad_overlay_click_close=\"yes\"><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c6a9ad elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"5c6a9ad\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-380acde exad-glass-effect-no exad-sticky-section-no\" data-id=\"380acde\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d64e4a2 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"d64e4a2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.2 - 29-01-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"exad-link-anything-wrapper elementor-section elementor-top-section elementor-element elementor-element-3196d96 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-exad-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/hagile.com.br\\\/projetos\\\/viegasultraimagem\\\/saude-ocupacional\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" data-id=\"3196d96\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19a2006 exad-glass-effect-no exad-sticky-section-no\" data-id=\"19a2006\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3b4571 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"a3b4571\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"exad-link-anything-wrapper elementor-section elementor-top-section elementor-element elementor-element-74125c8 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-exad-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/hagile.com.br\\\/projetos\\\/viegasultraimagem\\\/diagnostico-por-imagem\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" data-id=\"74125c8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b214c48 exad-glass-effect-no exad-sticky-section-no\" data-id=\"b214c48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9a7287 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"f9a7287\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a5347c elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"1a5347c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-acb31ac exad-glass-effect-no exad-sticky-section-no\" data-id=\"acb31ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8a0306 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-menu-anchor\" data-id=\"b8a0306\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"contato\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-259e9bf elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"259e9bf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f35b3cc exad-glass-effect-no exad-sticky-section-no\" data-id=\"f35b3cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-477eb05 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"477eb05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Entre em contato:<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d2449e elementor-button-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-form\" data-id=\"7d2449e\" data-element_type=\"widget\" data-settings=\"{&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.9.1 - 14-12-2022 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#c2cbd2}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"Formul\u00e1rio de Contato\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"9\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"7d2449e\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_dc1d849 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_dc1d849\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefone:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_dc1d849]\" id=\"form-field-field_dc1d849\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_da92bd8 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_da92bd8\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCidade\/Estado:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_da92bd8]\" id=\"form-field-field_da92bd8\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_fd17c5f elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_fd17c5f\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmpresa:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_fd17c5f]\" id=\"form-field-field_fd17c5f\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMensagem:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b3ea34f exad-glass-effect-no exad-sticky-section-no\" data-id=\"b3ea34f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c38f3c0 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"c38f3c0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">comunicacao@viegasultraimagem.com.br<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-volume\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(81) 3524-1071 | (81) 3521-1751<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(81) 97316-4377<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Av. Historiador Pereira da Costa, 520 - Centro, Cabo de Santo Agostinho - PE, 54510-360<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16330ba exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-google_maps\" data-id=\"16330ba\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.2 - 29-01-2023 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Av.%20Histo.%20Pereira%20da%20Costa%2C%20520%20-%20Centro%2C%20Cabo%20de%20Santo%20Agostinho%20-%20PE%2C%2054510-360&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Av. Histo. Pereira da Costa, 520 - Centro, Cabo de Santo Agostinho - PE, 54510-360\"\n\t\t\t\t\taria-label=\"Av. Histo. Pereira da Costa, 520 - Centro, Cabo de Santo Agostinho - PE, 54510-360\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a5cb54 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"7a5cb54\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d675c57 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"d675c57\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9b306d8 exad-glass-effect-no exad-sticky-section-no\" data-id=\"9b306d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d9be912 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"d9be912\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0aaff49 exad-glass-effect-no exad-sticky-section-no\" data-id=\"0aaff49\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd33c85 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"fd33c85\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Entre em contato:<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d74bdc4 elementor-button-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-form\" data-id=\"d74bdc4\" data-element_type=\"widget\" data-settings=\"{&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Formul\u00e1rio de Contato\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"9\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"d74bdc4\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_dc1d849 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_dc1d849\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefone:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_dc1d849]\" id=\"form-field-field_dc1d849\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_da92bd8 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_da92bd8\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCidade\/Estado:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_da92bd8]\" id=\"form-field-field_da92bd8\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_fd17c5f elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_fd17c5f\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmpresa:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_fd17c5f]\" id=\"form-field-field_fd17c5f\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMensagem:\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6aeb208 exad-glass-effect-no exad-sticky-section-no\" data-id=\"6aeb208\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88383e6 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"88383e6\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">comunicacao@viegasultraimagem.com.br<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/exames-ocupacionais\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-volume\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(81) 3524-1071 | (81) 3521-1751<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/message\/4C6BLVJGS7YPD1\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(81) 97316-4377<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Av. Historiador Pereira da Costa, 520 - Centro, Cabo de Santo Agostinho - PE, 54510-360<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b453df exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-google_maps\" data-id=\"1b453df\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Av.%20Histo.%20Pereira%20da%20Costa%2C%20520%20-%20Centro%2C%20Cabo%20de%20Santo%20Agostinho%20-%20PE%2C%2054510-360&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Av. Histo. Pereira da Costa, 520 - Centro, Cabo de Santo Agostinho - PE, 54510-360\"\n\t\t\t\t\taria-label=\"Av. Histo. Pereira da Costa, 520 - Centro, Cabo de Santo Agostinho - PE, 54510-360\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-48abebb exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"48abebb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99ff73e elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"99ff73e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-24edf04 exad-glass-effect-no exad-sticky-section-no\" data-id=\"24edf04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b94003 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"7b94003\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"224\" height=\"157\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/home-1.png\" class=\"attachment-large size-large wp-image-300\" alt=\"\" style=\"width:100%;height:70.09%;max-width:224px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-89fdae4 exad-glass-effect-no exad-sticky-section-no\" data-id=\"89fdae4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12b7c86 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"12b7c86\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Institucional<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-736b4bd exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"736b4bd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/\"><span style=\"color: #ffffff;\">In\u00edcio<\/span><\/a><br \/><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/quem-somos\/\"><span style=\"color: #ffffff;\">Quem Somos<\/span><\/a><br \/><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/#estrutura\"><span style=\"color: #ffffff;\">Nossa Estrutura<\/span><\/a><br \/><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/#contato\"><span style=\"color: #ffffff;\">Contato<\/span><\/a><br \/><a href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/politica-de-privacidade\/\"><span style=\"color: #ffffff;\">Pol\u00edtica de Privacidade<\/span><\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8669ca9 exad-glass-effect-no exad-sticky-section-no\" data-id=\"8669ca9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f096823 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"f096823\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Fale Conosco<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fdc790 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"6fdc790\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/message\/4C6BLVJGS7YPD1\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(81) 97316-4377<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:comunicacao@viegasultraimagem.com.br\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">comunicacao@viegasultraimagem.com.br<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:8135241071\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-volume\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(81) 3524-1071 | (81) 3521-1751<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fbca94c exad-glass-effect-no exad-sticky-section-no\" data-id=\"fbca94c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-889c10e exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"889c10e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Onde Estamos<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5705b24 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"5705b24\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Av. Historiador Pereira da Costa, 520 - Centro, Cabo de Santo Agostinho - PE, 54510-360<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-234b6eb elementor-shape-circle e-grid-align-left elementor-grid-0 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-social-icons\" data-id=\"234b6eb\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.2 - 29-01-2023 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)));height:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#818a91;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#818a91}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-4d29a35\" href=\"https:\/\/web.facebook.com\/viegasultraimagem\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-5d60abf\" href=\"https:\/\/www.instagram.com\/viegasultraimagem\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-5f98758\" href=\"https:\/\/www.linkedin.com\/company\/viegas-ultra-imagem\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f09c2b0 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"f09c2b0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-21b7a53 exad-glass-effect-no exad-sticky-section-no\" data-id=\"21b7a53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9164608 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"9164608\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"224\" height=\"157\" src=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-content\/uploads\/2021\/12\/home-1.png\" class=\"attachment-large size-large wp-image-300\" alt=\"\" style=\"width:100%;height:70.09%;max-width:224px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-55971bc exad-glass-effect-no exad-sticky-section-no\" data-id=\"55971bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7133f exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"3d7133f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Institucional<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b809c7a exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"b809c7a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#\"><span style=\"color: #ffffff;\">In\u00edcio<\/span><\/a><br \/><a href=\"#\"><span style=\"color: #ffffff;\">Quem Somos<\/span><\/a><br \/><a href=\"#\"><span style=\"color: #ffffff;\">Nossa Estrutura<\/span><\/a><br \/><a href=\"#\"><span style=\"color: #ffffff;\">Contato<\/span><\/a><br \/><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/politica-de-privacidade\/\">Pol\u00edtica de Privacidade<\/a><br \/><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-17878f2 exad-glass-effect-no exad-sticky-section-no\" data-id=\"17878f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27f89d1 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"27f89d1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Fale Conosco<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-831a713 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"831a713\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/message\/4C6BLVJGS7YPD1\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(81) 97316-4377<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:comunicacao@viegasultraimagem.com.br\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">comunicacao@viegasultraimagem.com.br<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:8135241071\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-volume\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(81) 3524-1071 | (81) 3521-1751<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2c6870b exad-glass-effect-no exad-sticky-section-no\" data-id=\"2c6870b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6743603 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"6743603\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Onde Estamos<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15ef22b elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"15ef22b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Av. Historiador Pereira da Costa, 520 - Centro, Cabo de Santo Agostinho - PE, 54510-360<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-347b5c2 elementor-shape-circle e-grid-align-left elementor-grid-0 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-social-icons\" data-id=\"347b5c2\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-4d29a35\" href=\"https:\/\/web.facebook.com\/viegasultraimagem\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-5d60abf\" href=\"https:\/\/www.instagram.com\/viegasultraimagem\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-5f98758\" href=\"https:\/\/www.linkedin.com\/company\/viegas-ultra-imagem\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a1bcf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"9a1bcf8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35a775b exad-glass-effect-no exad-sticky-section-no\" data-id=\"35a775b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5ae43e exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"a5ae43e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Desenvolvido por <a style=\"color: #ffffff;\" href=\"https:\/\/hagile.com.br\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"logo-hagile\" style=\"width: 20px;\" src=\"https:\/\/www.hagile.com.br\/img\/logo-hagile-simbolo.png\" alt=\"Hagile Ag\u00eancia Digital\" \/> Hagile Ag\u00eancia Digital<\/a><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>(81) 97316-4377 Whatsapp Av. Historiador Pereira da Costa, n\u00ba 520 Centro, Cabo de Sto Agostinho &#8211; PE comunicacao@viegasultraimagem.com.br Entre em contato conosco QUEM SOMOS A Ultra-Imagem Viegas \u00e9 um Centro Diagn\u00f3stico especializado em Radiologia e Sa\u00fade Ocupacional. Fundada em 2008 pelos m\u00e9dicos do trabalho e radiologistas Maria Rachel Viegas CRM-PE 12.813 e T\u00falio Br\u00e1ulio Cantalice&hellip; <a class=\"more-link\" href=\"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/\">Continuar lendo <span class=\"screen-reader-text\">In\u00edcio<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":656,"href":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":1436,"href":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-json\/wp\/v2\/pages\/9\/revisions\/1436"}],"wp:attachment":[{"href":"https:\/\/hagile.com.br\/projetos\/viegasultraimagem\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}